{"id":75936,"date":"2016-03-01T09:38:06","date_gmt":"2016-03-01T08:38:06","guid":{"rendered":"https:\/\/tcm.be\/glossarium\/acid-test-ratio\/"},"modified":"2026-05-07T15:14:23","modified_gmt":"2026-05-07T13:14:23","slug":"acid-test-ratio","status":"publish","type":"glossarium","link":"https:\/\/tcm.be\/de\/glossarium\/acid-test-ratio\/","title":{"rendered":"Acid-Test-Ratio"},"content":{"rendered":"\n<p>Die Acid-Test-Ratio misst die F\u00e4higkeit eines Unternehmens, seinen kurzfristigen Zahlungspflichten nachzukommen. Sie wird berechnet als das Umlaufverm\u00f6gen abz\u00fcglich der Vorr\u00e4te und der unfertigen Arbeiten, geteilt durch die kurzfristigen Verbindlichkeiten. Diese Kennzahl ist auch als Quick Ratio bekannt. Eine Quick Ratio von 1,00 bedeutet, dass 1 EUR Verbindlichkeiten durch 1 EUR kurzfristig verf\u00fcgbare Verm\u00f6genswerte gedeckt sind, w\u00e4hrend eine Quick Ratio von 0,50 als weniger sicher gilt. Updated 01\/03\/2016     <\/p>\n\n<p>Die unter diesem Punkt aufgef\u00fchrten Definitionen spiegeln die belgische Situation wider, sofern nicht anders angegeben. Die Texte dienen dazu, die Konzepte in Alltagssprache zusammenzufassen und sind nicht als umfassend oder endg\u00fcltig zu verstehen. Vorschl\u00e4ge oder Anpassungen k\u00f6nnen jederzeit an <a title=\"mail tcm\" href=\"mailto:glossary@tcm.be\">glossary@tcm.be<\/a> gesendet werden.  <\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-75936","glossarium","type-glossarium","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/tcm.be\/de\/wp-json\/wp\/v2\/glossarium\/75936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tcm.be\/de\/wp-json\/wp\/v2\/glossarium"}],"about":[{"href":"https:\/\/tcm.be\/de\/wp-json\/wp\/v2\/types\/glossarium"}],"wp:attachment":[{"href":"https:\/\/tcm.be\/de\/wp-json\/wp\/v2\/media?parent=75936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}