{"id":75937,"date":"2017-04-03T19:33:58","date_gmt":"2017-04-03T17:33:58","guid":{"rendered":"https:\/\/tcm.be\/glossarium\/mahn-und-forderungsmanagement\/"},"modified":"2026-05-07T15:18:55","modified_gmt":"2026-05-07T13:18:55","slug":"mahn-und-forderungsmanagement","status":"publish","type":"glossarium","link":"https:\/\/tcm.be\/de\/glossarium\/mahn-und-forderungsmanagement\/","title":{"rendered":"Mahn- und Forderungsmanagement"},"content":{"rendered":"\n<p>Das Forderungsmanagement ist eine Abteilung einer \u00f6ffentlichen Einrichtung oder eines privaten Unternehmens, deren Ziel es ist, s\u00e4mtliche Probleme im Zusammenhang mit versp\u00e4teten Zahlungen zu verwalten, wie etwa offene <a href=\"https:\/\/tcm.be\/factuur\/\">Rechnungen<\/a>, <a href=\"https:\/\/tcm.be\/factuur\/\">Forderungen <\/a>und deren <a href=\"https:\/\/tcm.be\/schuldvordering\/\">Einziehung<\/a>. Zur Erreichung dieser Ziele und zur Wahrung der Interessen der <a href=\"https:\/\/tcm.be\/schuldeiser\/\">Gl\u00e4ubiger <\/a>bedient sich das Debitorenmanagement verschiedener Verfahren, darunter der Versand von Zahlungs\u2011 oder rechtlichen Aufforderungsschreiben sowie die telefonische Kontaktaufnahme mit den <a href=\"https:\/\/tcm.be\/schuldenaar\/\">Schuldnern<\/a>. Die f\u00fcr das Debitorenmanagement Verantwortlichen k\u00f6nnen zudem auch mit der Bearbeitung anderer Streitigkeiten betraut sein, beispielsweise bei Reklamationen oder Unzufriedenheit mit einem Produkt oder einer Dienstleistung. Updated 03\/04\/2017   <\/p>\n\n<p>Die unter diesem Punkt aufgef\u00fchrten Definitionen spiegeln die belgische Situation wider, sofern nicht anders angegeben. Die Texte dienen dazu, die Konzepte in Alltagssprache zusammenzufassen und sind nicht als umfassend oder endg\u00fcltig zu verstehen. Vorschl\u00e4ge oder Anpassungen k\u00f6nnen jederzeit an <a href=\"mailto:glossary@tcm.be\">glossary@tcm.be<\/a> gesendet werden.  <\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-75937","glossarium","type-glossarium","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/tcm.be\/de\/wp-json\/wp\/v2\/glossarium\/75937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tcm.be\/de\/wp-json\/wp\/v2\/glossarium"}],"about":[{"href":"https:\/\/tcm.be\/de\/wp-json\/wp\/v2\/types\/glossarium"}],"wp:attachment":[{"href":"https:\/\/tcm.be\/de\/wp-json\/wp\/v2\/media?parent=75937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}